{"id":9788,"date":"2020-07-15T17:00:50","date_gmt":"2020-07-15T20:00:50","guid":{"rendered":"https:\/\/sigiweb.diegosoares.com.br\/?p=9788"},"modified":"2024-06-19T16:19:12","modified_gmt":"2024-06-19T19:19:12","slug":"comunicacao-social-nas-igrejas-parte-2","status":"publish","type":"post","link":"https:\/\/www.zeke.com.br\/blog\/comunicacao-social-nas-igrejas-parte-2\/","title":{"rendered":"Comunica\u00e7\u00e3o Social nas Igrejas Parte 2"},"content":{"rendered":"<p>No artigo anterior sobre esse assunto, acesse aqui <a href=\"https:\/\/www.zeke.com.br\/blog\/comunicacao-social-na-igreja\/\">Comunica\u00e7\u00e3o Social na Igreja<\/a>, trouxemos a defini\u00e7\u00e3o do termo Comunica\u00e7\u00e3o Social, bem como demos enfoque na parte de comunica\u00e7\u00e3o interna nas igrejas, essencial para que se tenha um ambiente organizado, harmonioso, prop\u00edcio ao crescimento esperado da igreja.<\/p>\n<p>Nesta primeira parte, enfocamos a necessidade de os gestores entenderem que n\u00e3o existe evangeliza\u00e7\u00e3o sem comunica\u00e7\u00e3o e que evangelizar \u00e9 uma necessidade para a igreja, seguindo o exemplo do Ap\u00f3stolo Paulo, entretanto, que a igreja tem que fazer a \u201cli\u00e7\u00e3o de casa\u201d, come\u00e7ar o seu projeto de comunica\u00e7\u00e3o dentro da pr\u00f3pria igreja.<\/p>\n<p>Sempre \u00e9 bom lembrar que a igreja existe para um prop\u00f3sito, a vida da igreja est\u00e1 baseada \u00fanica e exclusivamente neste prop\u00f3sito, levar o Evangelho a toda criatura, tudo mais \u00e9 acess\u00f3rio e, falando em comunica\u00e7\u00e3o, a rotina interna estando organizada a igreja deve ir para o pr\u00f3ximo passo, a comunica\u00e7\u00e3o externa.<\/p>\n<p>Antes, de adentrarmos ao assunto de fato, \u00e9 bom termos em mente que a igreja deve se fazer presente em todos os momentos na vida dos membros e, nas prega\u00e7\u00f5es ou fora delas, a comunica\u00e7\u00e3o \u00e9 a ferramenta fundamental para obter sucesso nessa empreitada.<\/p>\n<p>O m\u00e9dico Dana E. King no seu livro F\u00e9, Espiritualidade e Medicina, lan\u00e7ado pela editora The Haworth Press em Nova York, no ano 2000, descreve que existem diversos estudos cient\u00edficos reconhecidos que concluem que pessoas que se envolvem em atividades religiosas e espirituais possuem menos sinais de ansiedade, depress\u00e3o e inten\u00e7\u00f5es suicidas.<\/p>\n<p>O m\u00e9dico cita ainda que as pesquisas demonstram claramente que o envolvimento religioso \u00e9 um indicador de satisfa\u00e7\u00e3o e bem-estar, continuando, ele cita que dezenas de estudos mostram que pessoas envolvidas com religi\u00e3o e espiritualidade apresentam taxas muito menores de uso de subst\u00e2ncias qu\u00edmicas.<\/p>\n<p>\u00c9 claro que n\u00f3s j\u00e1 sab\u00edamos disso, para n\u00f3s \u00e9 a comprova\u00e7\u00e3o de forma indireta do grande poder de Deus agindo na vida daqueles que o servem, a nossa miss\u00e3o \u00e9 quebrar os paradigmas contempor\u00e2neos e propagar essa mensagem a todas as pessoas que querem e precisam ouvir o Evangelho de Jesus Cristo.<\/p>\n<p>Se quisermos mostrar as pessoas que na igreja, ao conhecer o Cristo verdadeiro, elas se sentir\u00e3o inseridas em um ambiente que trar\u00e1 conforto aos seus cora\u00e7\u00f5es e paz aos seus esp\u00edritos.<\/p>\n<p>Temos que deixar de lado alguns dogmas e abrir a nossa mente para o uso das ferramentas de comunica\u00e7\u00e3o tecnol\u00f3gicas existentes hoje para que possamos alcan\u00e7ar essas pessoas.<\/p>\n<h3>Mundo Moderno e Conectado<\/h3>\n<p>Nesse mundo moderno e conectado em que vivemos hoje, toda e qualquer organiza\u00e7\u00e3o, seja ela privada, p\u00fablica e mesmo do terceiro setor, como as igrejas, devem definir sua estrat\u00e9gia competitiva, sua miss\u00e3o e seus objetivos, junto com eles definir uma pol\u00edtica de melhorias cont\u00ednuas visando seu crescimento como entidade que participa da vida da comunidade ao seu redor.<\/p>\n<p>Desta forma, o seu processo de comunica\u00e7\u00e3o deve passar por atualiza\u00e7\u00f5es constantes, visando sua melhoria e adequa\u00e7\u00e3o aos tempos e a tecnologia atual, de forma que possa garantir que as mensagens dirigidas aos seus membros ser\u00e3o bem recepcionadas e entendidas de modo bastante claro.<\/p>\n<p>A comunica\u00e7\u00e3o deve ser encarada como uma ferramenta com o potencial de contribuir para que a igreja alcance seus objetivos, seja interna ou externamente.<\/p>\n<p>A igreja n\u00e3o pode ser uma ilha de informa\u00e7\u00e3o, ela deve estar inserida no seio da sua comunidade e distribuir a sua mensagem a todos e a comunica\u00e7\u00e3o \u00e9 uma poderosa ferramenta para isso.<\/p>\n<h3>Redes Sociais e as Igrejas<\/h3>\n<p>Com o advento da tecnologia, a comunica\u00e7\u00e3o deixou de ser uma via de m\u00e3o \u00fanica, as m\u00eddias sociais e outros canais online s\u00e3o fundamentais para a dissemina\u00e7\u00e3o do evangelho.<\/p>\n<p>Entretanto, como dissemos mais acima, deve haver um alinhamento entre as a\u00e7\u00f5es de comunica\u00e7\u00e3o com as estrat\u00e9gias e a miss\u00e3o principal da igreja.<\/p>\n<p>A populariza\u00e7\u00e3o da internet e o crescimento das redes sociais s\u00e3o um fen\u00f4meno cada vez mais presente no dia a dia das pessoas, segundo o Global Digital Report 2019 da We Are Social e Hootsuite, aproximadamente 57% da popula\u00e7\u00e3o global est\u00e1 presente na internet e 45% s\u00e3o usu\u00e1rios das redes sociais.<\/p>\n<p>Aqui, em terras tupiniquins, os n\u00fameros s\u00e3o melhores ainda, segundo esse mesmo estudo, 70% da nossa popula\u00e7\u00e3o \u00e9 usu\u00e1ria da internet e o Facebook, Instagram e o YouTube que s\u00e3o as tr\u00eas m\u00eddias sociais mais acessadas, contam com acesso de 66% dos brasileiros.<\/p>\n<p>A nossa inten\u00e7\u00e3o com este artigo n\u00e3o ensin\u00e1-lo a publicar ou dar dicas de utiliza\u00e7\u00e3o das m\u00eddias sociais para ajudar no crescimento da sua igreja.<\/p>\n<p>Entretanto, queremos mostrar a voc\u00ea que elas trazem uma grande oportunidade, uma forma de levar a mensagem da igreja e, obviamente a mensagem de Cristo, a milhares, talvez milh\u00f5es de pessoas, com alguns cliques.<\/p>\n<p>Al\u00e9m das tr\u00eas m\u00eddias sociais que citamos acima, existem ainda o Twitter e o WhatsApp, elas tamb\u00e9m podem ser utilizadas nas suas estrat\u00e9gias para alcan\u00e7ar mais pessoas para a igreja ou para conectar e levar uma mensagem nova aquelas que j\u00e1 fazem parte da nossa comunidade crist\u00e3.<\/p>\n<p>O uso da tecnologia tem transformado a gest\u00e3o de empresas e institui\u00e7\u00f5es mundo afora, \u00e9 essencial n\u00f3s entendermos que na igreja isso n\u00e3o pode ser diferente, muitas vezes estamos perdendo nosso precioso tempo focando em esfor\u00e7os e a\u00e7\u00f5es que j\u00e1 n\u00e3o funcionam mais, o papel da comunica\u00e7\u00e3o hoje funciona de maneira diferente, temos que compreender isso.<\/p>\n<p>\u00c9 claro que se voc\u00ea n\u00e3o tem conhecimento suficiente o melhor \u00e9 procurar ajuda profissional mas voc\u00ea j\u00e1 pode ir adiantando as coisas no seu planejamento, formule o seu objetivo, imagine o que voc\u00ea deseja alcan\u00e7ar com as suas publica\u00e7\u00f5es, por exemplo:<\/p>\n<p>Espalhar a mensagem da sua igreja, divulgar um evento que vai acontecer, entre outros, para que voc\u00ea n\u00e3o perca o foco, a mensagem precisa ser clara e objetiva.<\/p>\n<p>Uma outra coisa importante \u00e9 selecionar o seu p\u00fablico alvo, se voc\u00ea pretende fazer um evento para casais por exemplo, n\u00e3o teria sentido direcionar o convite para solteiros, simples assim.<\/p>\n<p>Ent\u00e3o sempre quando tiver uma mensagem para publicar \u00e9 grande import\u00e2ncia que voc\u00ea consiga definir qual o grupo de pessoas, nas redes sociais voc\u00ea consegue definir grupos por sexo, faixa et\u00e1ria, regi\u00e3o onde vivem, entre outras, esses filtros deixem a sua mensagem mais assertiva.<\/p>\n<p>O passo mais importante \u00e9 o conte\u00fado, \u00e9 ele que vai determinar o sucesso ou n\u00e3o da sua estrat\u00e9gia, devemos procurar algo que seja interessante e que tenha a capacidade de chamar a aten\u00e7\u00e3o das pessoas, aqui a sua criatividade vale ouro \u00e9 ela que vai contar.<\/p>\n<p>\u00c9 sempre bom lembrar que o conte\u00fado deve estar ligado ao objetivo que pretende alcan\u00e7ar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No artigo anterior sobre esse assunto, acesse aqui Comunica\u00e7\u00e3o Social na Igreja, trouxemos a defini\u00e7\u00e3o do termo Comunica\u00e7\u00e3o Social, bem como demos enfoque na parte de comunica\u00e7\u00e3o interna nas igrejas, essencial para que se tenha um ambiente organizado, harmonioso, prop\u00edcio ao crescimento esperado da igreja. Nesta primeira parte, enfocamos a necessidade de os gestores entenderem &#8230; <a title=\"Comunica\u00e7\u00e3o Social nas Igrejas Parte 2\" class=\"read-more\" href=\"https:\/\/www.zeke.com.br\/blog\/comunicacao-social-nas-igrejas-parte-2\/\" aria-label=\"Read more about Comunica\u00e7\u00e3o Social nas Igrejas Parte 2\">Ler mais<\/a><\/p>\n","protected":false},"author":4,"featured_media":11895,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[98],"tags":[],"class_list":["post-9788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestao-de-igrejas"],"_links":{"self":[{"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/posts\/9788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/comments?post=9788"}],"version-history":[{"count":2,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/posts\/9788\/revisions"}],"predecessor-version":[{"id":12269,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/posts\/9788\/revisions\/12269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/media\/11895"}],"wp:attachment":[{"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/media?parent=9788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/categories?post=9788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/tags?post=9788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}