{"id":8782,"date":"2017-07-17T15:00:17","date_gmt":"2017-07-17T18:00:17","guid":{"rendered":"https:\/\/zeke.com.br\/blog\/receita-federal-lanca-nova-versao-dctf-mensal\/"},"modified":"2024-04-03T11:09:12","modified_gmt":"2024-04-03T14:09:12","slug":"receita-federal-lanca-nova-versao-dctf-mensal","status":"publish","type":"post","link":"https:\/\/www.zeke.com.br\/blog\/receita-federal-lanca-nova-versao-dctf-mensal\/","title":{"rendered":"Receita Federal Lan\u00e7a Nova Vers\u00e3o da DCTF Mensal"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Atrav\u00e9s do Ato Declarat\u00f3rio Executivo Codac n\u00ba 16 foi aprovada e lan\u00e7ada a vers\u00e3o 3.4 do PGD da Declara\u00e7\u00e3o de D\u00e9bitos e Cr\u00e9ditos Tribut\u00e1rios Federais (DCTF) mensal.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Com a extin\u00e7\u00e3o da DSPJ \u2013 Inativas, as pessoas jur\u00eddicas obrigadas a apresent\u00e1-la passam agora a serem obrigadas a apresentar a DCTF Mensal para informar ao fisco essa situa\u00e7\u00e3o de inatividade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esta nova vers\u00e3o do PGD deve ser utilizada para a elabora\u00e7\u00e3o das DCTF, referentes aos per\u00edodos de apura\u00e7\u00e3o de janeiro a abril de 2017, das pessoas jur\u00eddicas inativas ou que n\u00e3o tenham d\u00e9bitos a declarar, cujo prazo de entrega vence em 21\/07\/2017.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para aquelas pessoas jur\u00eddicas que TENHAM D\u00c9BITOS A DECLARAR referente ao m\u00eas de Maio de 2017 a dctf mensal tamb\u00e9m deve ser entregue at\u00e9 dia 21\/07\/2017 e j\u00e1 deve ser utilizada a vers\u00e3o 3.4 do PGD da DCTF Mensal.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O nosso Sistema SigeRH j\u00e1 est\u00e1 preparado para exportar os dados na nova vers\u00e3o do PGD, portanto, se no m\u00eas de Maio de 2017 houve reten\u00e7\u00e3o de imposto de renda na fonte, tanto de prestadores sem v\u00ednculo de emprego, como pastores e aut\u00f4nomos ou de funcion\u00e1rios com contrato de trabalho, voc\u00ea deve atualizar o sistema para poder exportar os dados j\u00e1 para a nova vers\u00e3o da DCTF mensal, ou seja, a vers\u00e3o 3.4.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atrav\u00e9s do Ato Declarat\u00f3rio Executivo Codac n\u00ba 16 foi aprovada e lan\u00e7ada a vers\u00e3o 3.4 do PGD da Declara\u00e7\u00e3o de D\u00e9bitos e Cr\u00e9ditos Tribut\u00e1rios Federais (DCTF) mensal. Com a extin\u00e7\u00e3o da DSPJ \u2013 Inativas, as pessoas jur\u00eddicas obrigadas a apresent\u00e1-la passam agora a serem obrigadas a apresentar a DCTF Mensal para informar ao fisco essa &#8230; <a title=\"Receita Federal Lan\u00e7a Nova Vers\u00e3o da DCTF Mensal\" class=\"read-more\" href=\"https:\/\/www.zeke.com.br\/blog\/receita-federal-lanca-nova-versao-dctf-mensal\/\" aria-label=\"Read more about Receita Federal Lan\u00e7a Nova Vers\u00e3o da DCTF Mensal\">Ler mais<\/a><\/p>\n","protected":false},"author":4,"featured_media":8115,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[96],"tags":[],"class_list":["post-8782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contabilidade-para-igrejas"],"_links":{"self":[{"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/posts\/8782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/comments?post=8782"}],"version-history":[{"count":1,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/posts\/8782\/revisions"}],"predecessor-version":[{"id":12199,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/posts\/8782\/revisions\/12199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/media\/8115"}],"wp:attachment":[{"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/media?parent=8782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/categories?post=8782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/tags?post=8782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}