{"id":8742,"date":"2017-03-01T15:11:29","date_gmt":"2017-03-01T18:11:29","guid":{"rendered":"https:\/\/zeke.com.br\/blog\/igreja-devem-entregar-rais-em-17032017\/"},"modified":"2026-05-07T16:28:36","modified_gmt":"2026-05-07T19:28:36","slug":"igreja-devem-entregar-rais-em-17032017","status":"publish","type":"post","link":"https:\/\/www.zeke.com.br\/blog\/igreja-devem-entregar-rais-em-17032017\/","title":{"rendered":"Igreja Devem Entregar a RAIS no Dia 17\/03\/2017"},"content":{"rendered":"<h3>O Que \u00e9\u00a0a RAIS?<\/h3>\n<p>Abrevia\u00e7\u00e3o de Rela\u00e7\u00e3o Anual de Informa\u00e7\u00f5es Sociais, a RAIS \u00e9 um coletor de informa\u00e7\u00f5es sociais criado pelo governo brasileiro cujos dados s\u00e3o analisados e utilizados pelo Minist\u00e9rio do Trabalho e Emprego desde 1975.<\/p>\n<p>Al\u00e9m do uso para gera\u00e7\u00e3o de estat\u00edsticas diversas sobre a atividade trabalhista no pa\u00eds, sua principal fun\u00e7\u00e3o \u00e9 identificar os trabalhadores com direito ao abono do PIS\/PASEP.<\/p>\n<h3>Quem Deve Entregar a RAIS?<\/h3>\n<p>Devem entregar a RAIS:<\/p>\n<ul>\n<li>Todas as pessoas jur\u00eddicas inscritas no CNPJ com ou sem empregados no ano base;<\/li>\n<li>Todos os empregadores, conforme a defini\u00e7\u00e3o da CLT;<\/li>\n<li>Empresas individuais, inclusive as que n\u00e3o possuem empregados;<\/li>\n<li>Cart\u00f3rios e cons\u00f3rcios de empresas;<\/li>\n<li>Condom\u00ednios e sociedades civis;<\/li>\n<li>Entre outros.<\/li>\n<\/ul>\n<p>\u00c9 importante trazer a lume que as igrejas por possu\u00edrem CNPJ e se enquadrarem na condi\u00e7\u00e3o de empregadores EST\u00c3O OBRIGADAS a apresentar a RAIS, mesmo sem empregados.<\/p>\n<h3>O Prazo<\/h3>\n<p>Quem est\u00e1 obrigado a entregar a RAIS \u2013 Rela\u00e7\u00e3o Anual de Informa\u00e7\u00f5es Sociais dever\u00e1 faz\u00ea-lo at\u00e9 o dia 17 de mar\u00e7o de 2017.<\/p>\n<p>A declara\u00e7\u00e3o da RAIS \u00e9 feita pelo programa GDRais 2016. O envio dever\u00e1 ser feito somente via internet.<\/p>\n<p>Em caso de estabelecimento sem v\u00ednculos empregat\u00edcios no ano-base, dever\u00e1 ser utilizado o formul\u00e1rio pr\u00f3prio de Declara\u00e7\u00e3o de RAIS Negativa Web. Ambas as formas de declara\u00e7\u00e3o estar\u00e3o dispon\u00edveis no site <a href=\"http:\/\/www.rais.gov.br\/\" target=\"_blank\" rel=\"noopener\">www.rais.gov.br<\/a>.<\/p>\n<h3>Multa<\/h3>\n<p>Aquele que estiver obrigado a entregar a RAIS e n\u00e3o o faz\u00ea-lo no prazo estabelecido em lei sofrer\u00e1 as penalidades previstas.<\/p>\n<p>O valor m\u00ednimo da multa ser\u00e1 de R$ 425,64, esse valor varia de acordo com o n\u00famero de funcion\u00e1rios e o tempo de atraso podendo chegar at\u00e9 R$ 42.641,00.<\/p>\n<h3>Ministros de Confiss\u00e3o Religiosa<\/h3>\n<p>Pastores, Padres, Rabinos e outros considerados como Ministros de Confiss\u00e3o Religiosa que percebem os seus rendimentos conforme a lei e recolhem a contribui\u00e7\u00e3o previdenci\u00e1ria como contribuinte individual obrigat\u00f3rio N\u00c3O DEVEM SER RELACIONADOS na RAIS.<\/p>\n<p>O nosso sistema SigeRH est\u00e1 preparado para a gera\u00e7\u00e3o do arquivo a ser analisado pelo GDRAIS 2017 e como temos afinidade no trato com igrejas e institui\u00e7\u00f5es do terceiro setor j\u00e1 trata de separar os Ministros de Confiss\u00e3o Religiosa dos demais empregados que devem constar da RAIS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Que \u00e9\u00a0a RAIS? Abrevia\u00e7\u00e3o de Rela\u00e7\u00e3o Anual de Informa\u00e7\u00f5es Sociais, a RAIS \u00e9 um coletor de informa\u00e7\u00f5es sociais criado pelo governo brasileiro cujos dados s\u00e3o analisados e utilizados pelo Minist\u00e9rio do Trabalho e Emprego desde 1975. Al\u00e9m do uso para gera\u00e7\u00e3o de estat\u00edsticas diversas sobre a atividade trabalhista no pa\u00eds, sua principal fun\u00e7\u00e3o \u00e9 &#8230; <a title=\"Igreja Devem Entregar a RAIS no Dia 17\/03\/2017\" class=\"read-more\" href=\"https:\/\/www.zeke.com.br\/blog\/igreja-devem-entregar-rais-em-17032017\/\" aria-label=\"Read more about Igreja Devem Entregar a RAIS no Dia 17\/03\/2017\">Ler mais<\/a><\/p>\n","protected":false},"author":4,"featured_media":8747,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[98],"tags":[],"class_list":["post-8742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestao-de-igrejas"],"_links":{"self":[{"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/posts\/8742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/comments?post=8742"}],"version-history":[{"count":1,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/posts\/8742\/revisions"}],"predecessor-version":[{"id":12225,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/posts\/8742\/revisions\/12225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/media\/8747"}],"wp:attachment":[{"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/media?parent=8742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/categories?post=8742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/tags?post=8742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}