{"id":2671,"date":"2015-01-20T16:26:03","date_gmt":"2015-01-20T18:26:03","guid":{"rendered":"https:\/\/zeke.com.br\/blog\/tabelas-2015-ir-inss-salario-minimo\/"},"modified":"2026-05-07T16:28:16","modified_gmt":"2026-05-07T19:28:16","slug":"tabelas-2015-ir-inss-salario-minimo","status":"publish","type":"post","link":"https:\/\/www.zeke.com.br\/blog\/tabelas-2015-ir-inss-salario-minimo\/","title":{"rendered":"Tabelas 2015 &#8211; Imposto de Renda, INSS e Sal\u00e1rio M\u00ednimo"},"content":{"rendered":"<p>H\u00e1 algumas semanas hav\u00edamos publicado esse artigo com as novas tabelas de imposto de renda, INSS e sal\u00e1rio m\u00ednimo.<\/p>\n<p>Houve um erro de nossa parte em publicar uma tabela vinculada a Media Provis\u00f3ria 644, infelizmente o Congresso n\u00e3o fez a sua parte de votar a MP e ela perdeu a validade.<\/p>\n<p>Desta forma continua em vigor a tabela anterior do imposto de renda at\u00e9 que o governo se pronuncie e anuncie uma nova tabela devidamente corrigida.<\/p>\n<p>Pedimos desculpas pela nossa omiss\u00e3o. Quem j\u00e1 fechou a folha de Janeiro deste ano pode fazer um ajuste na folha de Fevereiro de 2015.<\/p>\n<p>Pedimos aos nossos clientes que utilizam o Sistema SigeRH que procedam a altera\u00e7\u00e3o da tabela do Imposto de Renda, conforme a tela abaixo:<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-2719\" src=\"https:\/\/zeke.com.br\/blog\/wp-content\/uploads\/2015\/01\/tabela-irrf-2015.jpg\" alt=\"Tabela IRRF 2015\" width=\"591\" height=\"332\" srcset=\"https:\/\/www.zeke.com.br\/blog\/wp-content\/uploads\/2015\/01\/tabela-irrf-2015.jpg 591w, https:\/\/www.zeke.com.br\/blog\/wp-content\/uploads\/2015\/01\/tabela-irrf-2015-300x169.jpg 300w\" sizes=\"(max-width: 591px) 100vw, 591px\" \/><\/p>\n<p>Da mesma forma, A Portaria Interministerial 13 MPS-MF, de 9-1-2015, publicada no Di\u00e1rio Oficial do dia 12\/01\/2015, reajustou em 6,23% os valores de contribui\u00e7\u00e3o da Tabela de Sal\u00e1rios de Contribui\u00e7\u00e3o aplic\u00e1vel aos segurados empregados, inclusive os dom\u00e9sticos, e os trabalhadores avulsos.<\/p>\n<p>Veja abaixo como fica a tabela a ser inserida no sistema SigeRH para ser utilizada a partir da compet\u00eancia Janeiro\/2015.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-2672\" src=\"https:\/\/zeke.com.br\/blog\/wp-content\/uploads\/2015\/01\/tabela-inss-2015.jpeg\" alt=\"Tabela INSS 2015\" width=\"590\" height=\"320\" srcset=\"https:\/\/www.zeke.com.br\/blog\/wp-content\/uploads\/2015\/01\/tabela-inss-2015.jpeg 590w, https:\/\/www.zeke.com.br\/blog\/wp-content\/uploads\/2015\/01\/tabela-inss-2015-300x163.jpeg 300w\" sizes=\"(max-width: 590px) 100vw, 590px\" \/><\/p>\n<p>N\u00e3o se esque\u00e7am tamb\u00e9m de alterar a tabela para o Sal\u00e1rio M\u00ednimo que foi para R$ 788,00.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e1 algumas semanas hav\u00edamos publicado esse artigo com as novas tabelas de imposto de renda, INSS e sal\u00e1rio m\u00ednimo. Houve um erro de nossa parte em publicar uma tabela vinculada a Media Provis\u00f3ria 644, infelizmente o Congresso n\u00e3o fez a sua parte de votar a MP e ela perdeu a validade. Desta forma continua em &#8230; <a title=\"Tabelas 2015 &#8211; Imposto de Renda, INSS e Sal\u00e1rio M\u00ednimo\" class=\"read-more\" href=\"https:\/\/www.zeke.com.br\/blog\/tabelas-2015-ir-inss-salario-minimo\/\" aria-label=\"Read more about Tabelas 2015 &#8211; Imposto de Renda, INSS e Sal\u00e1rio M\u00ednimo\">Ler mais<\/a><\/p>\n","protected":false},"author":4,"featured_media":2675,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[96],"tags":[],"class_list":["post-2671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contabilidade-para-igrejas"],"_links":{"self":[{"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/posts\/2671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2671"}],"version-history":[{"count":1,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/posts\/2671\/revisions"}],"predecessor-version":[{"id":12210,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/posts\/2671\/revisions\/12210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/media\/2675"}],"wp:attachment":[{"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zeke.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}